{"id":707,"count":1,"description":"Auto Added by WPeMatico","link":"https:\/\/newswiredelhi.com\/index.php\/category\/president\/","name":"President","slug":"president","taxonomy":"category","parent":0,"meta":{"category-image-id":[]},"image_url":"","_links":{"self":[{"href":"https:\/\/newswiredelhi.com\/index.php\/wp-json\/wp\/v2\/categories\/707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newswiredelhi.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/newswiredelhi.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/newswiredelhi.com\/index.php\/wp-json\/wp\/v2\/posts?categories=707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}